{"id":24,"count":5,"description":"","link":"https:\/\/www.behindthepinecurtain.com\/wordpress\/category\/linkup\/","name":"LINKUP","slug":"linkup","taxonomy":"category","parent":0,"meta":[],"_links":{"self":[{"href":"https:\/\/www.behindthepinecurtain.com\/wordpress\/wp-json\/wp\/v2\/categories\/24","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.behindthepinecurtain.com\/wordpress\/wp-json\/wp\/v2\/categories"}],"about":[{"href":"https:\/\/www.behindthepinecurtain.com\/wordpress\/wp-json\/wp\/v2\/taxonomies\/category"}],"wp:post_type":[{"href":"https:\/\/www.behindthepinecurtain.com\/wordpress\/wp-json\/wp\/v2\/posts?categories=24"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}